{"id":9905,"date":"2026-06-04T13:35:30","date_gmt":"2026-06-04T17:35:30","guid":{"rendered":"https:\/\/cis-group.com\/?p=9905"},"modified":"2026-07-02T10:04:01","modified_gmt":"2026-07-02T14:04:01","slug":"groupe-cis-prend-part-a-une-discussion-concrete-sur-ladoption-de-lia-organisee-par-la-bdc","status":"publish","type":"post","link":"https:\/\/cis-group.com\/fr\/groupe-cis-prend-part-a-une-discussion-concrete-sur-ladoption-de-lia-organisee-par-la-bdc\/","title":{"rendered":"Groupe CIS prend part \u00e0 une discussion concr\u00e8te sur l\u2019adoption de l\u2019IA, organis\u00e9e par la BDC"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le 3 juin, Groupe CIS a eu l\u2019occasion de participer \u00e0 un \u00e9v\u00e9nement organis\u00e9 par la <strong>Banque de d\u00e9veloppement du Canada (BDC)<\/strong>, consacr\u00e9 \u00e0 l\u2019adoption concr\u00e8te de l\u2019intelligence artificielle au sein des PME canadiennes. R\u00e9unissant une soixantaine de participants, l\u2019\u00e9v\u00e9nement rassemblait entrepreneurs, fournisseurs de solutions en IA, experts du domaine et autres acteurs de l\u2019\u00e9cosyst\u00e8me.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette rencontre visait \u00e0 favoriser des \u00e9changes francs et ancr\u00e9s dans la r\u00e9alit\u00e9 des organisations, loin des discours th\u00e9oriques, afin de mieux comprendre comment l\u2019IA peut soutenir la performance et la croissance des entreprises.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" data-id=\"9953\" src=\"https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-1-1200x1200.jpg\" alt=\"\" class=\"wp-image-9953\" srcset=\"https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-1-1200x1200.jpg 1200w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-1-300x300.jpg 300w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-1-150x150.jpg 150w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-1-768x768.jpg 768w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-1-1536x1536.jpg 1536w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-1.jpg 1600w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" data-id=\"9954\" src=\"https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-3-1200x1200.jpg\" alt=\"\" class=\"wp-image-9954\" srcset=\"https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-3-1200x1200.jpg 1200w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-3-300x300.jpg 300w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-3-150x150.jpg 150w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-3-768x768.jpg 768w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-3-1536x1536.jpg 1536w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-3.jpg 1600w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" data-id=\"9955\" src=\"https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-4-1200x1200.jpg\" alt=\"\" class=\"wp-image-9955\" srcset=\"https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-4-1200x1200.jpg 1200w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-4-300x300.jpg 300w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-4-150x150.jpg 150w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-4-768x768.jpg 768w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-4-1536x1536.jpg 1536w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-4.jpg 1600w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" data-id=\"9952\" src=\"https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-5-1200x1200.jpg\" alt=\"\" class=\"wp-image-9952\" srcset=\"https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-5-1200x1200.jpg 1200w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-5-300x300.jpg 300w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-5-150x150.jpg 150w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-5-768x768.jpg 768w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-5-1536x1536.jpg 1536w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-5.jpg 1600w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" data-id=\"9951\" src=\"https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-2-1200x1200.jpg\" alt=\"\" class=\"wp-image-9951\" srcset=\"https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-2-1200x1200.jpg 1200w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-2-300x300.jpg 300w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-2-150x150.jpg 150w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-2-768x768.jpg 768w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-2-1536x1536.jpg 1536w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-2.jpg 1600w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" data-id=\"9956\" src=\"https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-6-1200x1200.jpg\" alt=\"\" class=\"wp-image-9956\" srcset=\"https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-6-1200x1200.jpg 1200w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-6-300x300.jpg 300w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-6-150x150.jpg 150w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-6-768x768.jpg 768w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-6-1536x1536.jpg 1536w, https:\/\/cis-group.com\/wp-content\/uploads\/2026\/06\/bdc-6.jpg 1600w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 id=\"une-initiative-portee-par-la-bdc\" class=\"wp-block-heading\">Une initiative port\u00e9e par la BDC<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019\u00e9v\u00e9nement s\u2019est tenu au Square BDC \u00e0 Montr\u00e9al et s\u2019est ouvert par une allocution d\u2019<strong>Isabelle Hudon<\/strong>, pr\u00e9sidente et cheffe de la direction de la BDC. <strong>Pierre Cl\u00e9roux<\/strong>, \u00e9conomiste en chef, y a ensuite pr\u00e9sent\u00e9 les faits saillants de la plus r\u00e9cente \u00e9tude de la BDC sur l\u2019adoption de l\u2019IA et des technologies par les entreprises canadiennes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La discussion, anim\u00e9e par <strong>Sadhana Venkatesan<\/strong>, Vice-pr\u00e9sidente, Architecture technologique et services applicatifs, r\u00e9unissait :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Un fournisseur canadien de solutions en intelligence artificielle, <strong>Moov AI<\/strong>,<\/li>\n\n\n\n<li>Une entreprise ayant concr\u00e8tement int\u00e9gr\u00e9 l\u2019<a href=\"\/fr\/solutions\/cis-companion\/fonctionnalite-intelligence-artificielle\/\" target=\"_blank\" rel=\"noreferrer noopener\">IA dans ses op\u00e9rations<\/a>, <strong>Groupe CIS<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Cette diversit\u00e9 de profils a permis de croiser les points de vue strat\u00e9giques, technologiques et op\u00e9rationnels, dans un esprit de partage d\u2019exp\u00e9rience.<\/p>\n\n\n\n<h2 id=\"la-contribution-de-groupe-cis-et-de-moov-ai-a-la-discussion\" class=\"wp-block-heading\">La contribution de Groupe CIS et de Moov AI \u00e0 la discussion<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Invit\u00e9s par la <strong>BDC<\/strong> \u00e0 prendre part \u00e0 cet \u00e9change, <strong>Groupe CIS<\/strong> et <strong>Moov AI<\/strong> ont chacun contribu\u00e9 \u00e0 la discussion \u00e0 partir de leur r\u00f4le et de leur expertise respective.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cyrille<\/strong>, repr\u00e9sentant <strong>Groupe CIS<\/strong>, a partag\u00e9 l\u2019exp\u00e9rience de l\u2019organisation en mati\u00e8re d\u2019adoption de l\u2019intelligence artificielle, en mettant en lumi\u00e8re les apprentissages li\u00e9s \u00e0 l\u2019int\u00e9gration progressive de l\u2019<a href=\"\/fr\/solutions\/cis-companion\/fonctionnalite-intelligence-artificielle\/\" target=\"_blank\" rel=\"noreferrer noopener\">IA dans ses op\u00e9rations et ses solutions<\/a>. Les \u00e9changes ont notamment port\u00e9 sur l\u2019importance de partir de cas d\u2019usage concrets, d\u2019assurer une bonne gouvernance des donn\u00e9es et d\u2019accompagner les \u00e9quipes dans cette transformation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De son c\u00f4t\u00e9, <strong>Henik<\/strong> est intervenu au nom de <strong>Moov AI<\/strong>, en abordant les enjeux technologiques et les bonnes pratiques li\u00e9es au d\u00e9veloppement et au d\u00e9ploiement de solutions d\u2019intelligence artificielle adapt\u00e9es aux r\u00e9alit\u00e9s des organisations.<\/p>\n\n\n\n<h2 id=\"un-projet-developpe-avec-moov-ai-mis-de-l-avant-lors-de-l-evenement\" class=\"wp-block-heading\">Un projet d\u00e9velopp\u00e9 avec Moov AI, mis de l\u2019avant lors de l\u2019\u00e9v\u00e9nement<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Groupe CIS<\/strong> est tr\u00e8s heureux d\u2019avoir \u00e9t\u00e9 invit\u00e9 par la <strong>BDC<\/strong> \u00e0 participer \u00e0 cet \u00e9v\u00e9nement et de voir son <a href=\"\/fr\/solutions\/cis-companion\/fonctionnalite-intelligence-artificielle\/\" data-type=\"link\" data-id=\"\/fr\/solutions\/cis-companion\/fonctionnalite-intelligence-artificielle\/\" target=\"_blank\" rel=\"noreferrer noopener\">projet en intelligence artificielle<\/a>, d\u00e9velopp\u00e9 en partenariat avec <strong>Moov AI<\/strong>, mis de l\u2019avant dans le cadre de cette discussion.<\/p>\n\n\n\n<h2 id=\"en-savoir-plus-sur-notre-module-d-intelligence-artificielle\" class=\"wp-block-heading\">En savoir plus sur notre module d\u2019intelligence artificielle<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019intelligence artificielle d\u00e9velopp\u00e9e par <strong>Groupe CIS<\/strong> vise avant tout \u00e0 s\u2019int\u00e9grer de fa\u00e7on utile et responsable aux processus existants. En collaboration avec <strong>Moov AI<\/strong>, nous avons con\u00e7u des modules d\u2019IA int\u00e9gr\u00e9s \u00e0 nos solutions, notamment <a href=\"https:\/\/cis-group.com\/solutions\/cis-companion\/\" data-type=\"solutions\" data-id=\"4618\">CIS Companion<\/a>, afin de soutenir l\u2019automatisation de certaines t\u00e2ches, l\u2019analyse de donn\u00e9es et l\u2019aide \u00e0 la prise de d\u00e9cision.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour en apprendre davantage sur notre approche et sur les fonctionnalit\u00e9s de notre module d\u2019intelligence artificielle :<\/p>\n\n\n\n<div class=\"gspb_button_wrapper gspb_button-id-gsbp-a31df3f\" id=\"gspb_button-id-gsbp-a31df3f\"><a class=\"wp-block-greenshift-blocks-buttonbox gspb-buttonbox wp-element-button\" href=\"https:\/\/cis-group.com\/fr\/solutions\/cis-companion\/fonctionnalite-intelligence-artificielle\/\" target=\"_blank\" rel=\"noopener\"><span class=\"gspb-buttonbox-textwrap\"><span class=\"gspb-buttonbox-text\"><span class=\"gspb-buttonbox-title\">D\u00e9couvrir CIS Companion et ses modules IA<\/span><\/span><\/span><\/a><\/div>\n\n\n\n<h2 id=\"contribuer-a-un-dialogue-utile-pour-l-ecosysteme\" class=\"wp-block-heading\">Contribuer \u00e0 un dialogue utile pour l\u2019\u00e9cosyst\u00e8me<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Au\u2011del\u00e0 de notre participation, cet \u00e9v\u00e9nement a permis de nourrir des discussions \u00e0 valeur ajout\u00e9e entre acteurs de l\u2019\u00e9cosyst\u00e8me. <strong>Groupe CIS<\/strong> remercie la <strong>BDC<\/strong> pour l\u2019organisation de cette rencontre et pour son leadership dans la cr\u00e9ation d\u2019espaces d\u2019\u00e9change favorisant une meilleure compr\u00e9hension des enjeux li\u00e9s \u00e0 l\u2019intelligence artificielle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces initiatives sont essentielles pour d\u00e9mystifier l\u2019IA et encourager une adoption r\u00e9fl\u00e9chie, align\u00e9e sur les r\u00e9alit\u00e9s des entreprises canadiennes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 3 juin, Groupe CIS a eu l\u2019occasion de participer \u00e0 un \u00e9v\u00e9nement organis\u00e9 par la Banque de d\u00e9veloppement du Canada (BDC), consacr\u00e9 \u00e0 l\u2019adoption concr\u00e8te de l\u2019intelligence artificielle au sein des PME canadiennes. R\u00e9unissant une soixantaine de participants, l\u2019\u00e9v\u00e9nement rassemblait entrepreneurs, fournisseurs de solutions en IA, experts du domaine et autres acteurs de l\u2019\u00e9cosyst\u00e8me. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":9949,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_gspb_post_css":"#gspb_button-id-gsbp-a31df3f{display:flex;justify-content:flex-start}#gspb_button-id-gsbp-a31df3f .gspb-buttonbox-text{display:flex;flex-direction:column}#gspb_button-id-gsbp-a31df3f>.gspb-buttonbox{box-sizing:border-box}","footnotes":""},"categories":[44,43,42],"tags":[],"class_list":["post-9905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cis-companion-ventes-distribution","category-groupe-cis","category-nouvelles"],"acf":[],"_links":{"self":[{"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/posts\/9905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/comments?post=9905"}],"version-history":[{"count":3,"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/posts\/9905\/revisions"}],"predecessor-version":[{"id":10162,"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/posts\/9905\/revisions\/10162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/media\/9949"}],"wp:attachment":[{"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/media?parent=9905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/categories?post=9905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/tags?post=9905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}