{"id":3915,"date":"2025-07-15T14:52:02","date_gmt":"2025-07-15T18:52:02","guid":{"rendered":"https:\/\/xfnvseujal-staging.onrocket.site\/?p=3915"},"modified":"2026-07-03T15:56:06","modified_gmt":"2026-07-03T19:56:06","slug":"groupe-cis-et-moovai-lintelligence-artificielle-au-service-dune-distribution-plus-intelligente","status":"publish","type":"post","link":"https:\/\/cis-group.com\/fr\/groupe-cis-et-moovai-lintelligence-artificielle-au-service-dune-distribution-plus-intelligente\/","title":{"rendered":"Groupe CIS et MoovAI : L\u2019intelligence artificielle au service d\u2019une distribution plus intelligente"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Montr\u00e9al, le 10 juillet 2025 \u2013 Groupe CIS, chef de file en <a href=\"https:\/\/cis-group.com\/fr\/solutions\/cis-companion\/\" data-type=\"solutions\" data-id=\"1570\">solutions logicielles pour la livraison directe en magasin (DSD)<\/a>, pr\u00e9sente aujourd\u2019hui, en pr\u00e9sence du ministre f\u00e9d\u00e9ral de l\u2019Intelligence artificielle, l\u2019honorable Evan Solomon, son projet d\u2019innovation soutenu par Scale AI. En collaboration avec Moov AI, expert qu\u00e9b\u00e9cois en intelligence artificielle, Groupe CIS <a href=\"https:\/\/cis-group.com\/fr\/solutions\/cis-companion\/fonctionnalite-intelligence-artificielle\/\" data-type=\"solutions\" data-id=\"4233\" target=\"_blank\" rel=\"noreferrer noopener\">transforme la distribution directe gr\u00e2ce \u00e0 deux moteurs IA<\/a> : la commande pr\u00e9dictive et l\u2019optimisation de l\u2019assortiment produit par point de vente.<\/p>\n\n\n\n<h2 id=\"le-bon-produit-la-bonne-quantite-au-bon-endroit-au-bon-moment\" class=\"wp-block-heading\">Le bon produit, la bonne quantit\u00e9, au bon endroit, au bon moment<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ce projet permettra aux entreprises d\u2019anticiper les besoins des magasins gr\u00e2ce \u00e0 des donn\u00e9es concr\u00e8tes plut\u00f4t que l\u2019intuition. R\u00e9sultat : moins de pertes, plus de ventes, et une diminution significative du gaspillage alimentaire. La technologie recommande les bons produits, en bonnes quantit\u00e9s, au bon endroit et au bon moment. Une avanc\u00e9e qui b\u00e9n\u00e9ficiera \u00e0 l\u2019ensemble de la cha\u00eene d\u2019approvisionnement : du producteur jusqu\u2019aux consommateurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Mieux livrer, c\u2019est \u00eatre plus productif et gaspiller moins. Gr\u00e2ce \u00e0 l\u2019IA, nos distributeurs pourront y parvenir, et c\u2019est nous tous qui en b\u00e9n\u00e9ficierons \u00bb, d\u00e9clare <a href=\"https:\/\/cis-group.com\/fr\/equipe\/eric-tessier\/\" data-type=\"equipe\" data-id=\"6687\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c9ric Tessier<\/a>, pr\u00e9sident de Groupe CIS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Nous sommes fiers de contribuer \u00e0 ce projet avec notre expertise en IA. Ensemble, nous b\u00e2tissons des solutions concr\u00e8tes et responsables qui am\u00e9liorent la performance des entreprises tout en ayant un impact positif sur la soci\u00e9t\u00e9 \u00bb, affirme Dominic Danis, pr\u00e9sident de Moov AI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00e2ce \u00e0 cette innovation, les entreprises pourront mieux anticiper la demande, r\u00e9duire les pertes et offrir une meilleure disponibilit\u00e9 des produits en magasin.<\/p>\n\n\n\n<h2 id=\"a-propos-de-groupe-cis\" class=\"wp-block-heading\">\u00c0 propos de Groupe CIS<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Fond\u00e9e en 1977, Groupe CIS d\u00e9veloppe des solutions logicielles d\u00e9di\u00e9es aux entreprises de distribution et de repr\u00e9sentation. Avec plus de 80 clients dans le secteur alimentaire, sa solution phare CIS Companion est utilis\u00e9e quotidiennement pour optimiser la livraison directe en magasin partout en Am\u00e9rique du Nord.<\/p>\n\n\n\n<h2 id=\"a-propos-de-moovai\" class=\"wp-block-heading\">\u00c0 propos de MoovAI<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Moov AI est une entreprise canadienne sp\u00e9cialis\u00e9e en intelligence artificielle et en donn\u00e9es. Elle combine son sens aiguis\u00e9 des affaires et sa vaste expertise technologique afin de d\u00e9velopper des solutions d\u2019IA qui r\u00e9pondent aux besoins d\u2019affaires de ses clients. Moov AI fait maintenant partie de la famille Publicis Groupe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Montr\u00e9al, le 10 juillet 2025 \u2013 Groupe CIS, chef de file en solutions logicielles pour la livraison directe en magasin (DSD), pr\u00e9sente aujourd\u2019hui, en pr\u00e9sence du ministre f\u00e9d\u00e9ral de l\u2019Intelligence artificielle, l\u2019honorable Evan Solomon, son projet d\u2019innovation soutenu par Scale AI. En collaboration avec Moov AI, expert qu\u00e9b\u00e9cois en intelligence artificielle, Groupe CIS transforme la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3907,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_gspb_post_css":"","footnotes":""},"categories":[44,43,42,69],"tags":[],"class_list":["post-3915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cis-companion-ventes-distribution","category-groupe-cis","category-nouvelles","category-solutions"],"acf":[],"_links":{"self":[{"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/posts\/3915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/comments?post=3915"}],"version-history":[{"count":1,"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/posts\/3915\/revisions"}],"predecessor-version":[{"id":10349,"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/posts\/3915\/revisions\/10349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/media\/3907"}],"wp:attachment":[{"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/media?parent=3915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/categories?post=3915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cis-group.com\/fr\/wp-json\/wp\/v2\/tags?post=3915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}